{"id":4499,"date":"2024-11-14T21:45:33","date_gmt":"2024-11-14T21:45:33","guid":{"rendered":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637.jpg"},"modified":"2024-11-14T21:45:33","modified_gmt":"2024-11-14T21:45:33","slug":"img_20241115_090749_637","status":"inherit","type":"attachment","link":"https:\/\/glover.gen.nz\/wordpress\/hand-crank-conversion-vintage-singer\/img_20241115_090749_637\/","title":{"rendered":"IMG_20241115_090749_637"},"author":1,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":[],"class_list":["post-4499","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"135\" height=\"300\" src=\"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-135x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-135x300.jpg 135w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-462x1024.jpg 462w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-68x150.jpg 68w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-768x1701.jpg 768w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-693x1536.jpg 693w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-924x2048.jpg 924w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-100x222.jpg 100w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-150x332.jpg 150w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-200x443.jpg 200w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-300x665.jpg 300w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-450x997.jpg 450w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-600x1329.jpg 600w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-900x1994.jpg 900w, https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-scaled.jpg 1156w\" sizes=\"auto, (max-width: 135px) 100vw, 135px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1156,"height":2560,"file":"2024\/11\/IMG_20241115_090749_637-scaled.jpg","filesize":238442,"sizes":{"medium":{"file":"IMG_20241115_090749_637-135x300.jpg","width":135,"height":300,"filesize":7287,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-135x300.jpg"},"large":{"file":"IMG_20241115_090749_637-462x1024.jpg","width":462,"height":1024,"filesize":45902,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-462x1024.jpg"},"thumbnail":{"file":"IMG_20241115_090749_637-68x150.jpg","width":68,"height":150,"filesize":2888,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-68x150.jpg"},"medium_large":{"file":"IMG_20241115_090749_637-768x1701.jpg","width":768,"height":1701,"filesize":106675,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-768x1701.jpg"},"1536x1536":{"file":"IMG_20241115_090749_637-693x1536.jpg","width":693,"height":1536,"filesize":89610,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-693x1536.jpg"},"2048x2048":{"file":"IMG_20241115_090749_637-924x2048.jpg","width":924,"height":2048,"filesize":150790,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-924x2048.jpg"},"responsive-100":{"file":"IMG_20241115_090749_637-100x222.jpg","width":100,"height":222,"filesize":4842,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-100x222.jpg"},"responsive-150":{"file":"IMG_20241115_090749_637-150x332.jpg","width":150,"height":332,"filesize":8474,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-150x332.jpg"},"responsive-200":{"file":"IMG_20241115_090749_637-200x443.jpg","width":200,"height":443,"filesize":12879,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-200x443.jpg"},"responsive-300":{"file":"IMG_20241115_090749_637-300x665.jpg","width":300,"height":665,"filesize":23580,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-300x665.jpg"},"responsive-450":{"file":"IMG_20241115_090749_637-450x997.jpg","width":450,"height":997,"filesize":44379,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-450x997.jpg"},"responsive-600":{"file":"IMG_20241115_090749_637-600x1329.jpg","width":600,"height":1329,"filesize":69869,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-600x1329.jpg"},"responsive-900":{"file":"IMG_20241115_090749_637-900x1994.jpg","width":900,"height":1994,"filesize":143353,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-900x1994.jpg"},"full":{"file":"IMG_20241115_090749_637-scaled.jpg","width":1156,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-scaled.jpg"}},"image_meta":{"aperture":"1.8","credit":"","camera":"Power Armor 14","caption":"","created_timestamp":"1731661669","copyright":"","focal_length":"5.46","iso":"303","shutter_speed":"0.030003","title":"","orientation":"0","keywords":[]},"original_image":"IMG_20241115_090749_637.jpg"},"post":4482,"source_url":"https:\/\/glover.gen.nz\/wordpress\/wp-content\/uploads\/2024\/11\/IMG_20241115_090749_637-scaled.jpg","_links":{"self":[{"href":"https:\/\/glover.gen.nz\/wordpress\/wp-json\/wp\/v2\/media\/4499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glover.gen.nz\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/glover.gen.nz\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/glover.gen.nz\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/glover.gen.nz\/wordpress\/wp-json\/wp\/v2\/comments?post=4499"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":4482,"href":"https:\/\/glover.gen.nz\/wordpress\/wp-json\/wp\/v2\/posts\/4482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}